{"id":25329,"date":"2021-12-02T08:12:19","date_gmt":"2021-12-02T07:12:19","guid":{"rendered":"https:\/\/looking-for-soccer.com\/%club_base%\/%club%\/asse-saint-etienne-francia\/"},"modified":"2026-08-03T14:43:59","modified_gmt":"2026-08-03T13:43:59","slug":"asse-saint-etienne-francia","status":"publish","type":"product","link":"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/","title":{"rendered":"ASSE &#8211; Saint Etienne"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":50560,"template":"","meta":{"_acf_changed":false,"_members_access_role":[],"_members_access_error":""},"product_brand":[],"product_cat":[646,647,426,640,648,641,715,433,642,643,2344,644,645],"product_tag":[338,327,339,328,329,330,331,332,333],"club":[810],"region":[450,461],"period":[],"class_list":["post-25329","product","type-product","status-publish","has-post-thumbnail","product_cat-u15-es-es","product_cat-u16-es-es","product_cat-interno","product_cat-u9","product_cat-u17-es-es","product_cat-u10-es-es","product_cat-mejora","product_cat-externo","product_cat-u11-es-es","product_cat-u12-es-es","product_cat-mixto","product_cat-u13","product_cat-u14","product_tag-8-anos","product_tag-10-anos","product_tag-9-anos","product_tag-11-anos","product_tag-12-anos","product_tag-13-anos","product_tag-14-anos","product_tag-15-anos","product_tag-16-anos","club-asse-saint-etienne-es-es","region-europa","region-francia","duree-de-5-a-8-dias","duree-de-13-a-15-dias","FPrix-menos-de-500e","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<title>Campamento de f\u00fatbol ASSE 2026 - Reserva en L\u00ednea - Pago en 3 cuotas<\/title>\n<meta name=\"description\" content=\"\u00bfTe interesa este Campamento de F\u00fatbol ASSE para tus hijos? Reserva en l\u00ednea f\u00e1cil &amp; 100% segura - Pago en 3 cuotas - Atenci\u00f3n al Cliente las 24\/7\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campamento de f\u00fatbol ASSE 2026 - Reserva en L\u00ednea - Pago en 3 cuotas\" \/>\n<meta property=\"og:description\" content=\"\u00bfTe interesa este Campamento de F\u00fatbol ASSE para tus hijos? Reserva en l\u00ednea f\u00e1cil &amp; 100% segura - Pago en 3 cuotas - Atenci\u00f3n al Cliente las 24\/7\" \/>\n<meta property=\"og:url\" content=\"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/\" \/>\n<meta property=\"og:site_name\" content=\"Looking for Soccer\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-03T13:43:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/looking-for-soccer.com\/wp-content\/uploads\/2021\/12\/Stage-foot-ete-ASSE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/es-es\\\/campamentos-futbol-club\\\/asse-saint-etienne-es-es\\\/asse-saint-etienne-francia\\\/\",\"url\":\"https:\\\/\\\/looking-for-soccer.com\\\/es-es\\\/campamentos-futbol-club\\\/asse-saint-etienne-es-es\\\/asse-saint-etienne-francia\\\/\",\"name\":\"Campamento de f\u00fatbol ASSE 2026 - Reserva en L\u00ednea - Pago en 3 cuotas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/en-us\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/es-es\\\/campamentos-futbol-club\\\/asse-saint-etienne-es-es\\\/asse-saint-etienne-francia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/es-es\\\/campamentos-futbol-club\\\/asse-saint-etienne-es-es\\\/asse-saint-etienne-francia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/looking-for-soccer.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Stage-foot-ete-ASSE.jpg\",\"datePublished\":\"2021-12-02T07:12:19+00:00\",\"dateModified\":\"2026-08-03T13:43:59+00:00\",\"description\":\"\u00bfTe interesa este Campamento de F\u00fatbol ASSE para tus hijos? Reserva en l\u00ednea f\u00e1cil & 100% segura - Pago en 3 cuotas - Atenci\u00f3n al Cliente las 24\\\/7\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/es-es\\\/campamentos-futbol-club\\\/asse-saint-etienne-es-es\\\/asse-saint-etienne-francia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/looking-for-soccer.com\\\/es-es\\\/campamentos-futbol-club\\\/asse-saint-etienne-es-es\\\/asse-saint-etienne-francia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/es-es\\\/campamentos-futbol-club\\\/asse-saint-etienne-es-es\\\/asse-saint-etienne-francia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/looking-for-soccer.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Stage-foot-ete-ASSE.jpg\",\"contentUrl\":\"https:\\\/\\\/looking-for-soccer.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Stage-foot-ete-ASSE.jpg\",\"width\":600,\"height\":400,\"caption\":\"Stage foot \u00e9t\u00e9 ASSE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/es-es\\\/campamentos-futbol-club\\\/asse-saint-etienne-es-es\\\/asse-saint-etienne-francia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/looking-for-soccer.com\\\/es-es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mejores Campamentos Futbol\",\"item\":\"https:\\\/\\\/looking-for-soccer.com\\\/es-es\\\/mejores-campamentos-futbol\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ASSE &#8211; Saint Etienne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/en-us\\\/#website\",\"url\":\"https:\\\/\\\/looking-for-soccer.com\\\/en-us\\\/\",\"name\":\"Looking for Soccer\",\"description\":\"Just another WordPress site\",\"publisher\":{\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/en-us\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/looking-for-soccer.com\\\/en-us\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/en-us\\\/#organization\",\"name\":\"Looking for Soccer\",\"url\":\"https:\\\/\\\/looking-for-soccer.com\\\/en-us\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/en-us\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/looking-for-soccer.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/looking-for-soccer-stages-football.svg\",\"contentUrl\":\"https:\\\/\\\/looking-for-soccer.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/looking-for-soccer-stages-football.svg\",\"caption\":\"Looking for Soccer\"},\"image\":{\"@id\":\"https:\\\/\\\/looking-for-soccer.com\\\/en-us\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"Campamento de f\u00fatbol ASSE 2026 - Reserva en L\u00ednea - Pago en 3 cuotas","description":"\u00bfTe interesa este Campamento de F\u00fatbol ASSE para tus hijos? Reserva en l\u00ednea f\u00e1cil & 100% segura - Pago en 3 cuotas - Atenci\u00f3n al Cliente las 24\/7","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/","og_locale":"es_ES","og_type":"article","og_title":"Campamento de f\u00fatbol ASSE 2026 - Reserva en L\u00ednea - Pago en 3 cuotas","og_description":"\u00bfTe interesa este Campamento de F\u00fatbol ASSE para tus hijos? Reserva en l\u00ednea f\u00e1cil & 100% segura - Pago en 3 cuotas - Atenci\u00f3n al Cliente las 24\/7","og_url":"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/","og_site_name":"Looking for Soccer","article_modified_time":"2026-08-03T13:43:59+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/looking-for-soccer.com\/wp-content\/uploads\/2021\/12\/Stage-foot-ete-ASSE.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/","url":"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/","name":"Campamento de f\u00fatbol ASSE 2026 - Reserva en L\u00ednea - Pago en 3 cuotas","isPartOf":{"@id":"https:\/\/looking-for-soccer.com\/en-us\/#website"},"primaryImageOfPage":{"@id":"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/#primaryimage"},"image":{"@id":"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/#primaryimage"},"thumbnailUrl":"https:\/\/looking-for-soccer.com\/wp-content\/uploads\/2021\/12\/Stage-foot-ete-ASSE.jpg","datePublished":"2021-12-02T07:12:19+00:00","dateModified":"2026-08-03T13:43:59+00:00","description":"\u00bfTe interesa este Campamento de F\u00fatbol ASSE para tus hijos? Reserva en l\u00ednea f\u00e1cil & 100% segura - Pago en 3 cuotas - Atenci\u00f3n al Cliente las 24\/7","breadcrumb":{"@id":"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/#primaryimage","url":"https:\/\/looking-for-soccer.com\/wp-content\/uploads\/2021\/12\/Stage-foot-ete-ASSE.jpg","contentUrl":"https:\/\/looking-for-soccer.com\/wp-content\/uploads\/2021\/12\/Stage-foot-ete-ASSE.jpg","width":600,"height":400,"caption":"Stage foot \u00e9t\u00e9 ASSE"},{"@type":"BreadcrumbList","@id":"https:\/\/looking-for-soccer.com\/es-es\/campamentos-futbol-club\/asse-saint-etienne-es-es\/asse-saint-etienne-francia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/looking-for-soccer.com\/es-es\/"},{"@type":"ListItem","position":2,"name":"Mejores Campamentos Futbol","item":"https:\/\/looking-for-soccer.com\/es-es\/mejores-campamentos-futbol\/"},{"@type":"ListItem","position":3,"name":"ASSE &#8211; Saint Etienne"}]},{"@type":"WebSite","@id":"https:\/\/looking-for-soccer.com\/en-us\/#website","url":"https:\/\/looking-for-soccer.com\/en-us\/","name":"Looking for Soccer","description":"Just another WordPress site","publisher":{"@id":"https:\/\/looking-for-soccer.com\/en-us\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/looking-for-soccer.com\/en-us\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/looking-for-soccer.com\/en-us\/#organization","name":"Looking for Soccer","url":"https:\/\/looking-for-soccer.com\/en-us\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/looking-for-soccer.com\/en-us\/#\/schema\/logo\/image\/","url":"https:\/\/looking-for-soccer.com\/wp-content\/uploads\/2021\/11\/looking-for-soccer-stages-football.svg","contentUrl":"https:\/\/looking-for-soccer.com\/wp-content\/uploads\/2021\/11\/looking-for-soccer-stages-football.svg","caption":"Looking for Soccer"},"image":{"@id":"https:\/\/looking-for-soccer.com\/en-us\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/looking-for-soccer.com\/es-es\/wp-json\/wp\/v2\/product\/25329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/looking-for-soccer.com\/es-es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/looking-for-soccer.com\/es-es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/looking-for-soccer.com\/es-es\/wp-json\/wp\/v2\/media\/50560"}],"wp:attachment":[{"href":"https:\/\/looking-for-soccer.com\/es-es\/wp-json\/wp\/v2\/media?parent=25329"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/looking-for-soccer.com\/es-es\/wp-json\/wp\/v2\/product_brand?post=25329"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/looking-for-soccer.com\/es-es\/wp-json\/wp\/v2\/product_cat?post=25329"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/looking-for-soccer.com\/es-es\/wp-json\/wp\/v2\/product_tag?post=25329"},{"taxonomy":"club","embeddable":true,"href":"https:\/\/looking-for-soccer.com\/es-es\/wp-json\/wp\/v2\/club?post=25329"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/looking-for-soccer.com\/es-es\/wp-json\/wp\/v2\/region?post=25329"},{"taxonomy":"period","embeddable":true,"href":"https:\/\/looking-for-soccer.com\/es-es\/wp-json\/wp\/v2\/period?post=25329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}